{"id":44103,"count":25,"description":"","link":"https:\/\/www.rizoma.com\/en\/motorbike\/harley-davidson\/road-glide\/road-glide-special-anniversary-2023\/","name":"Road Glide Special Anniversary (2023)","slug":"road-glide-special-anniversary-2023","taxonomy":"rizoma_bike","parent":44031,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rizoma.com\/en\/wp-json\/wp\/v2\/rizoma_bike\/44103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rizoma.com\/en\/wp-json\/wp\/v2\/rizoma_bike"}],"about":[{"href":"https:\/\/www.rizoma.com\/en\/wp-json\/wp\/v2\/taxonomies\/rizoma_bike"}],"up":[{"embeddable":true,"href":"https:\/\/www.rizoma.com\/en\/wp-json\/wp\/v2\/rizoma_bike\/44031"}],"wp:post_type":[{"href":"https:\/\/www.rizoma.com\/en\/wp-json\/wp\/v2\/product?rizoma_bike=44103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}