{"id":41589,"count":0,"description":"","link":"https:\/\/www.rizoma.com\/de\/motorbike\/bmw\/r-1200-s\/r-1200-s-1\/","name":"R 1200 S","slug":"r-1200-s-1","taxonomy":"rizoma_bike","parent":41104,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike\/41589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike"}],"about":[{"href":"https:\/\/www.rizoma.com\/de\/wp-json\/wp\/v2\/taxonomies\/rizoma_bike"}],"up":[{"embeddable":true,"href":"https:\/\/www.rizoma.com\/de\/wp-json\/wp\/v2\/rizoma_bike\/41104"}],"wp:post_type":[{"href":"https:\/\/www.rizoma.com\/de\/wp-json\/wp\/v2\/product?rizoma_bike=41589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}